{"id":109192,"date":"2021-10-15T15:49:45","date_gmt":"2021-10-15T21:49:45","guid":{"rendered":"http:\/\/www.sporthiva.com\/?p=109192"},"modified":"2021-10-15T15:49:45","modified_gmt":"2021-10-15T21:49:45","slug":"fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador","status":"publish","type":"post","link":"http:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/","title":{"rendered":"FIFA castiga a Panam\u00e1 a jugar sin p\u00fablico ante El Salvador"},"content":{"rendered":"<h4><strong>La FEPAFUT inform\u00f3 que la FIFA sancion\u00f3 el estadio Rommel Fern\u00e1ndez tras los hechos ocurridos el pasado 10 de octubre durante el partido entre Panam\u00e1 y Estados Unidos<\/strong><\/h4>\n<p><strong>Panam\u00e1<\/strong><\/p>\n<p>El partido entre Panam\u00e1 y El Salvador, del pr\u00f3ximo 16 de noviembre, en el estadio Rommel Fern\u00e1ndez se jugar\u00e1 sin p\u00fablico, seg\u00fan inform\u00f3 la Federaci\u00f3n Paname\u00f1a de F\u00fatbol.<\/p>\n<p>La FEPAFUT inform\u00f3 que la FIFA sancion\u00f3 el estadio Rommel Fern\u00e1ndez tras los hechos ocurridos el pasado 10 de octubre durante el partido entre Panam\u00e1 y Estados Unidos (1-0) en donde aficionados invadieron la cancha, adem\u00e1s que otras personas lanzaron balones.<\/p>\n<p><strong>Vea adem\u00e1s: <\/strong><a href=\"http:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-sanciona-a-chile-con-multa-y-reduccion-de-aforo-por-actos-discriminatorios-de-hinchas\/\"><strong>FIFA sanciona a Chile con multa y reducci\u00f3n de aforo por actos discriminatorios de hinchas<\/strong><\/a><\/p>\n<p>La FIFA, tambi\u00e9n, puso una sanci\u00f3n econ\u00f3mica de 50 mil francos suizos a la FEPAFUT, quien buscar\u00e1 apelar a la decisi\u00f3n de la ente rectora para poder tener p\u00fablico en su partido ante La Selecta el pr\u00f3ximo 16 de noviembre en casa.<\/p>\n<p>Panam\u00e1 no es la primera selecci\u00f3n castigada durante las eliminatorias y es que la selecci\u00f3n mexicana recibi\u00f3 el mismo castigo tras varios avisos por el grito homof\u00f3bico, por lo que tuvo que jugar el duelo ante Jamaica de la primera fecha a puerta cerrada.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">\u00a1ATENCI\u00d3N!<\/p>\n<p>FEPAFUT informa que ha sido notificada por la FIFA sobre la decisi\u00f3n tomada por su Comisi\u00f3n Disciplinaria de sancionar con 50 mil francos suizos y disputar el partido contra El Salvador\ud83c\uddf8\ud83c\uddfb a puerta cerrada.<\/p>\n<p>\u27a1\ufe0f <a href=\"https:\/\/t.co\/nb3NACOzPX\">https:\/\/t.co\/nb3NACOzPX<\/a><a href=\"https:\/\/twitter.com\/hashtag\/TodosSomosPanam%C3%A1?src=hash&amp;ref_src=twsrc%5Etfw\">#TodosSomosPanam\u00e1<\/a>\ud83c\uddf5\ud83c\udde6 <a href=\"https:\/\/t.co\/l3IGJloDuT\">pic.twitter.com\/l3IGJloDuT<\/a><\/p>\n<p>\u2014 FEPAFUT (@fepafut) <a href=\"https:\/\/twitter.com\/fepafut\/status\/1449112162769776640?ref_src=twsrc%5Etfw\">October 15, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La FEPAFUT inform\u00f3 que la FIFA sancion\u00f3 el estadio Rommel Fern\u00e1ndez tras los hechos ocurridos el pasado 10 de octubre durante el partido entre Panam\u00e1 y Estados Unidos Panam\u00e1 El partido entre Panam\u00e1 y El Salvador, del pr\u00f3ximo 16 de noviembre, en el estadio Rommel Fern\u00e1ndez se jugar\u00e1 sin p\u00fablico, seg\u00fan inform\u00f3 la Federaci\u00f3n Paname\u00f1a&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"http:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/\">Continuar leyendo<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"qubely_global_settings":"","qubely_interactions":""},"categories":[563],"tags":[277,35,185,1038],"qubely_featured_image_url":null,"qubely_author":{"display_name":"Evelyn Pineda","author_link":"http:\/\/www.sporthiva.com\/index.php\/author\/epineda\/"},"qubely_comment":0,"qubely_category":"<a href=\"http:\/\/www.sporthiva.com\/index.php\/category\/internacionales\/\" rel=\"category tag\">Internacionales<\/a>","qubely_excerpt":"La FEPAFUT inform\u00f3 que la FIFA sancion\u00f3 el estadio Rommel Fern\u00e1ndez tras los hechos ocurridos el pasado 10 de octubre durante el partido entre Panam\u00e1 y Estados Unidos Panam\u00e1 El partido entre Panam\u00e1 y El Salvador, del pr\u00f3ximo 16 de noviembre, en el estadio Rommel Fern\u00e1ndez se jugar\u00e1 sin p\u00fablico, seg\u00fan inform\u00f3 la Federaci\u00f3n Paname\u00f1a&nbsp;Continuar&hellip;","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FIFA castiga a Panam\u00e1 a jugar sin p\u00fablico ante El Salvador - Sporthiva Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIFA castiga a Panam\u00e1 a jugar sin p\u00fablico ante El Salvador - Sporthiva Online\" \/>\n<meta property=\"og:description\" content=\"La FEPAFUT inform\u00f3 que la FIFA sancion\u00f3 el estadio Rommel Fern\u00e1ndez tras los hechos ocurridos el pasado 10 de octubre durante el partido entre Panam\u00e1 y Estados Unidos Panam\u00e1 El partido entre Panam\u00e1 y El Salvador, del pr\u00f3ximo 16 de noviembre, en el estadio Rommel Fern\u00e1ndez se jugar\u00e1 sin p\u00fablico, seg\u00fan inform\u00f3 la Federaci\u00f3n Paname\u00f1a&nbsp;Continuar leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/\" \/>\n<meta property=\"og:site_name\" content=\"Sporthiva Online\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T21:49:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Pineda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.sporthiva.com\/#website\",\"url\":\"http:\/\/www.sporthiva.com\/\",\"name\":\"Sporthiva Online\",\"description\":\"Sporthiva Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.sporthiva.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/#webpage\",\"url\":\"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/\",\"name\":\"FIFA castiga a Panam\\u00e1 a jugar sin p\\u00fablico ante El Salvador - Sporthiva Online\",\"isPartOf\":{\"@id\":\"http:\/\/www.sporthiva.com\/#website\"},\"datePublished\":\"2021-10-15T21:49:45+00:00\",\"dateModified\":\"2021-10-15T21:49:45+00:00\",\"author\":{\"@id\":\"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/www.sporthiva.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIFA castiga a Panam\\u00e1 a jugar sin p\\u00fablico ante El Salvador\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611\",\"name\":\"Evelyn Pineda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.sporthiva.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g\",\"caption\":\"Evelyn Pineda\"},\"sameAs\":[\"http:\/\/www.sporthiva.com\/\"],\"url\":\"http:\/\/www.sporthiva.com\/index.php\/author\/epineda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FIFA castiga a Panam\u00e1 a jugar sin p\u00fablico ante El Salvador - Sporthiva Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/","og_locale":"es_ES","og_type":"article","og_title":"FIFA castiga a Panam\u00e1 a jugar sin p\u00fablico ante El Salvador - Sporthiva Online","og_description":"La FEPAFUT inform\u00f3 que la FIFA sancion\u00f3 el estadio Rommel Fern\u00e1ndez tras los hechos ocurridos el pasado 10 de octubre durante el partido entre Panam\u00e1 y Estados Unidos Panam\u00e1 El partido entre Panam\u00e1 y El Salvador, del pr\u00f3ximo 16 de noviembre, en el estadio Rommel Fern\u00e1ndez se jugar\u00e1 sin p\u00fablico, seg\u00fan inform\u00f3 la Federaci\u00f3n Paname\u00f1a&nbsp;Continuar leyendo","og_url":"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/","og_site_name":"Sporthiva Online","article_published_time":"2021-10-15T21:49:45+00:00","twitter_card":"summary","twitter_misc":{"Escrito por":"Evelyn Pineda","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/www.sporthiva.com\/#website","url":"http:\/\/www.sporthiva.com\/","name":"Sporthiva Online","description":"Sporthiva Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sporthiva.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/#webpage","url":"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/","name":"FIFA castiga a Panam\u00e1 a jugar sin p\u00fablico ante El Salvador - Sporthiva Online","isPartOf":{"@id":"http:\/\/www.sporthiva.com\/#website"},"datePublished":"2021-10-15T21:49:45+00:00","dateModified":"2021-10-15T21:49:45+00:00","author":{"@id":"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611"},"breadcrumb":{"@id":"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sporthiva.com\/index.php\/2021\/10\/15\/fifa-castiga-a-panama-a-jugar-sin-publico-ante-el-salvador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.sporthiva.com\/"},{"@type":"ListItem","position":2,"name":"FIFA castiga a Panam\u00e1 a jugar sin p\u00fablico ante El Salvador"}]},{"@type":"Person","@id":"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611","name":"Evelyn Pineda","image":{"@type":"ImageObject","@id":"http:\/\/www.sporthiva.com\/#personlogo","inLanguage":"es","url":"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g","caption":"Evelyn Pineda"},"sameAs":["http:\/\/www.sporthiva.com\/"],"url":"http:\/\/www.sporthiva.com\/index.php\/author\/epineda\/"}]}},"_links":{"self":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/109192"}],"collection":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/comments?post=109192"}],"version-history":[{"count":2,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/109192\/revisions"}],"predecessor-version":[{"id":109195,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/109192\/revisions\/109195"}],"wp:attachment":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/media?parent=109192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/categories?post=109192"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/tags?post=109192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}