{"id":137722,"date":"2023-04-14T15:39:01","date_gmt":"2023-04-14T21:39:01","guid":{"rendered":"http:\/\/www.sporthiva.com\/?p=137722"},"modified":"2023-04-14T15:39:01","modified_gmt":"2023-04-14T21:39:01","slug":"cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion","status":"publish","type":"post","link":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/","title":{"rendered":"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\u00f3n"},"content":{"rendered":"<p><strong>Cremona, Italia<\/strong><\/p>\n<p>El Cremonese, pen\u00faltimo en la clasificaci\u00f3n, con la mirada desde hace tiempo tendente a la Serie B, se aferra a sus opciones de salvaci\u00f3n al obtener su segunda victoria consecutiva, ante el Empoli en el estadio Giovanni Zin (1-0), en su encuentro de la trig\u00e9sima jornada.<\/p>\n<p>A falta de ocho cap\u00edtulos para el cierre del curso, el conjunto de Davide Ballardini se sit\u00faa a siete puntos del Specia, cuarto por la cola, que marca la permanencia.<\/p>\n<p>Tiene complicado el Cremonese alargar su estancia en la Serie A a pesar del aceler\u00f3n en los \u00faltimos partidos, pero todav\u00eda se aferra a sus posibilidades.<\/p>\n<p><strong>Vea adem\u00e1s: <\/strong><a href=\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/exesposa-de-jugador-del-psg-achraf-hakimi-reclamo-la-mitad-de-su-fortuna-pero-estaba-a-nombre-de-su-madre\/\"><strong>Exesposa de jugador del PSG Achraf Hakimi reclam\u00f3 la mitad de su fortuna pero estaba a nombre de su madre<\/strong><\/a><\/p>\n<p>El cuadro de Ballardini rentabiliz\u00f3 el gol logrado, el \u00fanico del partido, a los cuatro minutos ante un rival sin nada en juego. El Empoli es decimocuarto, pero diez puntos le distancian de los tres \u00faltimos lugares de la tabla.<\/p>\n<div id=\"diariomas_728x90_300x250_Dynamic1\" class=\"fs-dynamic\" data-slot=\"complete\" data-freestar-ad=\"__728x90  __300x250 __fsAncillary\">\n<div>\n<p data-inc=\"1\">El gol naci\u00f3 en un pase largo, casi desde el medio del campo, de Leonardo Semicola al \u00e1rea visitante. Lo recogi\u00f3 el nigeriano Cyriel Dessers, que aprovech\u00f3 el error y la fragilidad del central Koni de Winter para batir a Samuele Perisan.<\/p>\n<p>El Cremonese resguard\u00f3 su ventaja y cerr\u00f3 el triunfo, el tercero en lo que va de Serie A y el segundo consecutivo, para mantener la confianza en la salvaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cremona, Italia El Cremonese, pen\u00faltimo en la clasificaci\u00f3n, con la mirada desde hace tiempo tendente a la Serie B, se aferra a sus opciones de salvaci\u00f3n al obtener su segunda victoria consecutiva, ante el Empoli en el estadio Giovanni Zin (1-0), en su encuentro de la trig\u00e9sima jornada. A falta de ocho cap\u00edtulos para el&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/\">Continuar leyendo<\/a><\/p>\n","protected":false},"author":7,"featured_media":137723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"qubely_global_settings":"","qubely_interactions":""},"categories":[563],"tags":[1860,1904,1781],"qubely_featured_image_url":{"full":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg",1200,800,false],"landscape":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-1200x750.jpg",1200,750,true],"portraits":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-540x320.jpg",540,320,true],"thumbnail":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-150x150.jpg",150,150,true],"medium":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-569x379.jpg",569,379,true],"medium_large":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-768x512.jpg",768,512,true],"large":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-1080x720.jpg",1080,720,true],"1536x1536":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg",1200,800,false],"2048x2048":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg",1200,800,false],"alm-thumbnail":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-150x150.jpg",150,150,true],"qubely_landscape":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-1200x750.jpg",1200,750,true],"qubely_portrait":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-540x320.jpg",540,320,true],"qubely_thumbnail":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-140x100.jpg",140,100,true],"sportspress-crop-medium":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-300x300.jpg",300,300,true],"sportspress-fit-medium":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-300x200.jpg",300,200,true],"sportspress-fit-icon":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-128x85.jpg",128,85,true],"sportspress-fit-mini":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-32x21.jpg",32,21,true],"heighlights":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-460x500.jpg",460,500,true],"video-thumb":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-360x235.jpg",360,235,true],"video-thumb2":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-360x422.jpg",360,422,true],"blog-thumb":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-175x150.jpg",175,150,true],"blog-medium":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-750x350.jpg",750,350,true],"blog-full":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-1140x550.jpg",1140,550,true],"popular-post":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-560x510.jpg",560,510,true],"heighlights-post":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-262x236.jpg",262,236,true],"player-thumb":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-270x150.jpg",270,150,true],"wp_rp_thumbnail":["http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24-150x150.jpg",150,150,true]},"qubely_author":{"display_name":"Evelyn Pineda","author_link":"http:\/\/www.sporthiva.com\/index.php\/author\/epineda\/"},"qubely_comment":0,"qubely_category":"<a href=\"http:\/\/www.sporthiva.com\/index.php\/category\/internacionales\/\" rel=\"category tag\">Internacionales<\/a>","qubely_excerpt":"Cremona, Italia El Cremonese, pen\u00faltimo en la clasificaci\u00f3n, con la mirada desde hace tiempo tendente a la Serie B, se aferra a sus opciones de salvaci\u00f3n al obtener su segunda victoria consecutiva, ante el Empoli en el estadio Giovanni Zin (1-0), en su encuentro de la trig\u00e9sima jornada. A falta de ocho cap\u00edtulos para el&nbsp;Continuar&hellip;","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\u00f3n - Sporthiva Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\u00f3n - Sporthiva Online\" \/>\n<meta property=\"og:description\" content=\"Cremona, Italia El Cremonese, pen\u00faltimo en la clasificaci\u00f3n, con la mirada desde hace tiempo tendente a la Serie B, se aferra a sus opciones de salvaci\u00f3n al obtener su segunda victoria consecutiva, ante el Empoli en el estadio Giovanni Zin (1-0), en su encuentro de la trig\u00e9sima jornada. A falta de ocho cap\u00edtulos para el&nbsp;Continuar leyendo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Sporthiva Online\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-14T21:39:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Pineda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.sporthiva.com\/#website\",\"url\":\"http:\/\/www.sporthiva.com\/\",\"name\":\"Sporthiva Online\",\"description\":\"Sporthiva Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.sporthiva.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg\",\"contentUrl\":\"http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#webpage\",\"url\":\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/\",\"name\":\"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\\u00f3n - Sporthiva Online\",\"isPartOf\":{\"@id\":\"http:\/\/www.sporthiva.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#primaryimage\"},\"datePublished\":\"2023-04-14T21:39:01+00:00\",\"dateModified\":\"2023-04-14T21:39:01+00:00\",\"author\":{\"@id\":\"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.sporthiva.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611\",\"name\":\"Evelyn Pineda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.sporthiva.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g\",\"caption\":\"Evelyn Pineda\"},\"sameAs\":[\"http:\/\/www.sporthiva.com\/\"],\"url\":\"http:\/\/www.sporthiva.com\/index.php\/author\/epineda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\u00f3n - Sporthiva Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/","og_locale":"es_ES","og_type":"article","og_title":"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\u00f3n - Sporthiva Online","og_description":"Cremona, Italia El Cremonese, pen\u00faltimo en la clasificaci\u00f3n, con la mirada desde hace tiempo tendente a la Serie B, se aferra a sus opciones de salvaci\u00f3n al obtener su segunda victoria consecutiva, ante el Empoli en el estadio Giovanni Zin (1-0), en su encuentro de la trig\u00e9sima jornada. A falta de ocho cap\u00edtulos para el&nbsp;Continuar leyendo","og_url":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/","og_site_name":"Sporthiva Online","article_published_time":"2023-04-14T21:39:01+00:00","og_image":[{"width":1200,"height":800,"url":"http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Evelyn Pineda","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/www.sporthiva.com\/#website","url":"http:\/\/www.sporthiva.com\/","name":"Sporthiva Online","description":"Sporthiva Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sporthiva.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#primaryimage","inLanguage":"es","url":"http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg","contentUrl":"http:\/\/www.sporthiva.com\/wp-content\/uploads\/2023\/04\/1200x800-58be110fa8bff62513e4c09444404e24.jpg","width":1200,"height":800},{"@type":"WebPage","@id":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#webpage","url":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/","name":"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\u00f3n - Sporthiva Online","isPartOf":{"@id":"http:\/\/www.sporthiva.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#primaryimage"},"datePublished":"2023-04-14T21:39:01+00:00","dateModified":"2023-04-14T21:39:01+00:00","author":{"@id":"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611"},"breadcrumb":{"@id":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.sporthiva.com\/index.php\/2023\/04\/14\/cremonese-se-impone-por-1-0-a-empoli-y-se-aferra-a-la-salvacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sporthiva.com\/"},{"@type":"ListItem","position":2,"name":"Cremonese se impone por 1-0 a Empoli y se aferra a la salvaci\u00f3n"}]},{"@type":"Person","@id":"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611","name":"Evelyn Pineda","image":{"@type":"ImageObject","@id":"http:\/\/www.sporthiva.com\/#personlogo","inLanguage":"es","url":"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g","caption":"Evelyn Pineda"},"sameAs":["http:\/\/www.sporthiva.com\/"],"url":"http:\/\/www.sporthiva.com\/index.php\/author\/epineda\/"}]}},"_links":{"self":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/137722"}],"collection":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/comments?post=137722"}],"version-history":[{"count":1,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/137722\/revisions"}],"predecessor-version":[{"id":137724,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/137722\/revisions\/137724"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/media\/137723"}],"wp:attachment":[{"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/media?parent=137722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/categories?post=137722"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/tags?post=137722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}