{"id":164426,"date":"2024-05-05T10:37:50","date_gmt":"2024-05-05T16:37:50","guid":{"rendered":"http:\/\/www.sporthiva.com\/?p=164426"},"modified":"2024-05-05T10:37:50","modified_gmt":"2024-05-05T16:37:50","slug":"tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024","status":"publish","type":"post","link":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/","title":{"rendered":"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024"},"content":{"rendered":"<p><strong><span class=\"t-location\">Santuario d&#8217;Oropa, Piamonte, Italia<\/span><\/strong><\/p>\n<p>El ciclista esloveno Tadej Pogacar fue el vencedor de la segunda etapa del Giro de Italia y gracias a ello se coloc\u00f3 como l\u00edder de la clasificaci\u00f3n general, este domingo en el santuario d&#8217;Oropa, en la regi\u00f3n del Piamonte.<\/p>\n<p>Tuvo este domingo un peque\u00f1o susto al caerse despu\u00e9s de un pinchazo durante la \u00faltima subida del d\u00eda, pero pudo seguir sin problemas y acabar triunfando en la meta, con 27 segundos de ventaja sobre el colombiano Daniel Mart\u00ednez (2\u00ba) y el gal\u00e9s Geraint Thomas (3\u00ba).<\/p>\n<p>En la general, Pogacar tiene ahora 45 segundos de margen respecto a Thomas y Mart\u00ednez.<\/p>\n<p><strong>Vea adem\u00e1s: <\/strong><a href=\"http:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/el-real-madrid-celebrara-la-liga-con-su-aficion-el-proximo-domingo-12-de-mayo\/\"><strong>El Real Madrid celebrar\u00e1 la Liga con su afici\u00f3n el pr\u00f3ximo domingo 12 de mayo<\/strong><\/a><\/p>\n<p>El hombre que hab\u00eda logrado la &#8216;maglia rosa&#8217; el s\u00e1bado al triunfar en la primera etapa, el ecuatoriano Jhonatan Narv\u00e1ez, fue trig\u00e9simo en la etapa, a 2 minutos y 3 segundos de Pogacar.<\/p>\n<p>Tras su percance, Pogacar, l\u00edder del equipo UAE, fue esperado por dos compa\u00f1eros y pudo reincorporarse r\u00e1pidamente al pelot\u00f3n de favoritos, antes de lanzar su ataque a cuatro kil\u00f3metros del final, acelerando en la subida final.<\/p>\n<p>Pogacar es el gran favorito al t\u00edtulo en esta 107\u00aa edici\u00f3n del Giro, que terminar\u00e1 el 26 de mayo en Roma, y aspira en este 2024 a ser el primero desde Marco Pantini en 1998 en conseguir un doblete Giro de Italia-Tour de Francia el mismo a\u00f1o.<\/p>\n<p>Pantani ya gan\u00f3 una etapa del Tour de Francia de 1999 en Oropa y tambi\u00e9n con un problema en carrera, en su caso una salida de la cadena en el inicio de la subida. El &#8216;Pirata&#8217; tambi\u00e9n supo reaccionar e imponer su ritmo para ser el ganador en aquella ocasi\u00f3n.<\/p>\n<p><strong>Le interesa tambi\u00e9n: <a href=\"http:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/el-psv-campeon-de-la-liga-holandesa-por-vigesimo-quinta-vez\/\">El PSV, campe\u00f3n de la liga holandesa por vig\u00e9simo quinta vez<\/a><\/strong><\/p>\n<p>Pogacar participa por primera vez en el Giro y puede ahora presumir de formar parte del selecto club de corredores que han ganado etapas en las tres grandes rondas por etapas (Francia, Italia y Espa\u00f1a).<\/p>\n<p>\u00abUno de mis sue\u00f1os era lograr ese triplete en las grandes rondas, pocos ciclistas lo consiguieron\u00bb, explic\u00f3 este domingo. \u00abNo tuve miedo [despu\u00e9s de la ca\u00edda]. Hubo un poco de confusi\u00f3n con el coche. Pero todo est\u00e1 bien\u00bb, se\u00f1al\u00f3.<\/p>\n<p>\u00abNos hab\u00edamos planteado atacar a tres o cuatro kil\u00f3metros de la meta. No conoc\u00edamos muy bien la \u00faltima subida, pero hicimos un buen trabajo. El objetivo era ganar la etapa y conseguir la &#8216;maglia rosa&#8217;. Se ha conseguido y vamos a poder estar tranquilos las pr\u00f3ximas etapas, que son favorables para las llegadas al esprint\u00bb, insisti\u00f3 el dos veces (2020, 2021) ganador del Tour de Francia. (Con informaci\u00f3n de AFP).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santuario d&#8217;Oropa, Piamonte, Italia El ciclista esloveno Tadej Pogacar fue el vencedor de la segunda etapa del Giro de Italia y gracias a ello se coloc\u00f3 como l\u00edder de la clasificaci\u00f3n general, este domingo en el santuario d&#8217;Oropa, en la regi\u00f3n del Piamonte. Tuvo este domingo un peque\u00f1o susto al caerse despu\u00e9s de un pinchazo&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/\">Continuar leyendo<\/a><\/p>\n","protected":false},"author":7,"featured_media":164427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"qubely_global_settings":"","qubely_interactions":""},"categories":[561],"tags":[4248,7913],"qubely_featured_image_url":{"full":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg",1200,675,false],"landscape":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg",1200,675,false],"portraits":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-540x320.jpg",540,320,true],"thumbnail":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-150x150.jpg",150,150,true],"medium":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-675x379.jpg",675,379,true],"medium_large":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-768x432.jpg",768,432,true],"large":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg",1200,675,false],"1536x1536":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg",1200,675,false],"2048x2048":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg",1200,675,false],"alm-thumbnail":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-150x150.jpg",150,150,true],"qubely_landscape":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg",1200,675,false],"qubely_portrait":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-540x320.jpg",540,320,true],"qubely_thumbnail":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-140x100.jpg",140,100,true],"sportspress-crop-medium":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-300x300.jpg",300,300,true],"sportspress-fit-medium":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-300x169.jpg",300,169,true],"sportspress-fit-icon":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-128x72.jpg",128,72,true],"sportspress-fit-mini":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-32x18.jpg",32,18,true],"heighlights":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-460x500.jpg",460,500,true],"video-thumb":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-360x235.jpg",360,235,true],"video-thumb2":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-360x422.jpg",360,422,true],"blog-thumb":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-175x150.jpg",175,150,true],"blog-medium":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-750x350.jpg",750,350,true],"blog-full":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-1140x550.jpg",1140,550,true],"popular-post":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-560x510.jpg",560,510,true],"heighlights-post":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-262x236.jpg",262,236,true],"player-thumb":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-270x150.jpg",270,150,true],"wp_rp_thumbnail":["https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0-150x150.jpg",150,150,true]},"qubely_author":{"display_name":"Evelyn Pineda","author_link":"https:\/\/www.sporthiva.com\/index.php\/author\/epineda\/"},"qubely_comment":0,"qubely_category":"<a href=\"https:\/\/www.sporthiva.com\/index.php\/category\/otros-deportes\/\" rel=\"category tag\">Otros deportes<\/a>","qubely_excerpt":"Santuario d&#8217;Oropa, Piamonte, Italia El ciclista esloveno Tadej Pogacar fue el vencedor de la segunda etapa del Giro de Italia y gracias a ello se coloc\u00f3 como l\u00edder de la clasificaci\u00f3n general, este domingo en el santuario d&#8217;Oropa, en la regi\u00f3n del Piamonte. Tuvo este domingo un peque\u00f1o susto al caerse despu\u00e9s de un pinchazo&nbsp;Continuar&hellip;","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tadej Pogacar gana la segunda etapa del Giro de Italia 2024 - Sporthiva Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024 - Sporthiva Online\" \/>\n<meta property=\"og:description\" content=\"Santuario d&#8217;Oropa, Piamonte, Italia El ciclista esloveno Tadej Pogacar fue el vencedor de la segunda etapa del Giro de Italia y gracias a ello se coloc\u00f3 como l\u00edder de la clasificaci\u00f3n general, este domingo en el santuario d&#8217;Oropa, en la regi\u00f3n del Piamonte. Tuvo este domingo un peque\u00f1o susto al caerse despu\u00e9s de un pinchazo&nbsp;Continuar leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Sporthiva Online\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T16:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Pineda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.sporthiva.com\/#website\",\"url\":\"http:\/\/www.sporthiva.com\/\",\"name\":\"Sporthiva Online\",\"description\":\"Sporthiva Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.sporthiva.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg\",\"contentUrl\":\"https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#webpage\",\"url\":\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/\",\"name\":\"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024 - Sporthiva Online\",\"isPartOf\":{\"@id\":\"http:\/\/www.sporthiva.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#primaryimage\"},\"datePublished\":\"2024-05-05T16:37:50+00:00\",\"dateModified\":\"2024-05-05T16:37:50+00:00\",\"author\":{\"@id\":\"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.sporthiva.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611\",\"name\":\"Evelyn Pineda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.sporthiva.com\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g\",\"caption\":\"Evelyn Pineda\"},\"sameAs\":[\"http:\/\/www.sporthiva.com\/\"],\"url\":\"https:\/\/www.sporthiva.com\/index.php\/author\/epineda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024 - Sporthiva Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024 - Sporthiva Online","og_description":"Santuario d&#8217;Oropa, Piamonte, Italia El ciclista esloveno Tadej Pogacar fue el vencedor de la segunda etapa del Giro de Italia y gracias a ello se coloc\u00f3 como l\u00edder de la clasificaci\u00f3n general, este domingo en el santuario d&#8217;Oropa, en la regi\u00f3n del Piamonte. Tuvo este domingo un peque\u00f1o susto al caerse despu\u00e9s de un pinchazo&nbsp;Continuar leyendo","og_url":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/","og_site_name":"Sporthiva Online","article_published_time":"2024-05-05T16:37:50+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Evelyn Pineda","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/www.sporthiva.com\/#website","url":"http:\/\/www.sporthiva.com\/","name":"Sporthiva Online","description":"Sporthiva Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sporthiva.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#primaryimage","inLanguage":"es","url":"https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg","contentUrl":"https:\/\/www.sporthiva.com\/wp-content\/uploads\/2024\/05\/POGACAR8ad63aa_16-9-discover-aspect-ratio_default_0.jpg","width":1200,"height":675},{"@type":"WebPage","@id":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#webpage","url":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/","name":"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024 - Sporthiva Online","isPartOf":{"@id":"http:\/\/www.sporthiva.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#primaryimage"},"datePublished":"2024-05-05T16:37:50+00:00","dateModified":"2024-05-05T16:37:50+00:00","author":{"@id":"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611"},"breadcrumb":{"@id":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sporthiva.com\/index.php\/2024\/05\/05\/tadej-pogacar-gana-la-segunda-etapa-del-giro-de-italia-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sporthiva.com\/"},{"@type":"ListItem","position":2,"name":"Tadej Pogacar gana la segunda etapa del Giro de Italia 2024"}]},{"@type":"Person","@id":"http:\/\/www.sporthiva.com\/#\/schema\/person\/551718db343e60bf7d707f9085b1e611","name":"Evelyn Pineda","image":{"@type":"ImageObject","@id":"http:\/\/www.sporthiva.com\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73932ff8109aee94864b4504adf4d91e?s=96&d=mm&r=g","caption":"Evelyn Pineda"},"sameAs":["http:\/\/www.sporthiva.com\/"],"url":"https:\/\/www.sporthiva.com\/index.php\/author\/epineda\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/164426"}],"collection":[{"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/comments?post=164426"}],"version-history":[{"count":1,"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/164426\/revisions"}],"predecessor-version":[{"id":164428,"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/posts\/164426\/revisions\/164428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/media\/164427"}],"wp:attachment":[{"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/media?parent=164426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/categories?post=164426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sporthiva.com\/index.php\/wp-json\/wp\/v2\/tags?post=164426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}